{"id":8,"count":38,"description":"","link":"https:\/\/www.baronedefensefirm.com\/blog\/category\/dui-enforcement\/","name":"DUI Enforcement","slug":"dui-enforcement","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DUI Enforcement Category Archives &#8212; Michigan Criminal Defense Lawyer Blog Published by Michigan Criminal Defense Attorney \u2014 Barone Defense Firm<\/title>\n<meta name=\"description\" content=\"Michigan Criminal Defense Lawyer Blog &#8212; DUI Enforcement Category &#8212; Michigan Criminal Defense Lawyer Blog\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.baronedefensefirm.com\/blog\/category\/dui-enforcement\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"DUI Enforcement Category Archives &#8212; Michigan Criminal Defense Lawyer Blog Published by Michigan Criminal Defense Attorney \u2014 Barone Defense Firm\" \/>\n<meta name=\"twitter:description\" content=\"Michigan Criminal Defense Lawyer Blog &#8212; DUI Enforcement Category &#8212; Michigan Criminal Defense Lawyer Blog\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DUI Enforcement Category Archives &#8212; Michigan Criminal Defense Lawyer Blog Published by Michigan Criminal Defense Attorney \u2014 Barone Defense Firm","description":"Michigan Criminal Defense Lawyer Blog &#8212; DUI Enforcement Category &#8212; Michigan Criminal Defense Lawyer Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.baronedefensefirm.com\/blog\/category\/dui-enforcement\/","twitter_card":"summary_large_image","twitter_title":"DUI Enforcement Category Archives &#8212; Michigan Criminal Defense Lawyer Blog Published by Michigan Criminal Defense Attorney \u2014 Barone Defense Firm","twitter_description":"Michigan Criminal Defense Lawyer Blog &#8212; DUI Enforcement Category &#8212; Michigan Criminal Defense Lawyer Blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.baronedefensefirm.com\/blog\/category\/dui-enforcement\/","url":"https:\/\/www.baronedefensefirm.com\/blog\/category\/dui-enforcement\/","name":"DUI Enforcement Category Archives &#8212; Michigan Criminal Defense Lawyer Blog Published by Michigan Criminal Defense Attorney \u2014 Barone Defense Firm","isPartOf":{"@id":"https:\/\/www.baronedefensefirm.com\/blog\/#website"},"description":"Michigan Criminal Defense Lawyer Blog &#8212; DUI Enforcement Category &#8212; Michigan Criminal Defense Lawyer Blog","breadcrumb":{"@id":"https:\/\/www.baronedefensefirm.com\/blog\/category\/dui-enforcement\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.baronedefensefirm.com\/blog\/category\/dui-enforcement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.baronedefensefirm.com\/blog\/"},{"@type":"ListItem","position":2,"name":"DUI Enforcement"}]},{"@type":"WebSite","@id":"https:\/\/www.baronedefensefirm.com\/blog\/#website","url":"https:\/\/www.baronedefensefirm.com\/blog\/","name":"Michigan Criminal Defense Lawyer Blog","description":"Published by Michigan Criminal Defense Attorney \u2014 Barone Defense Firm","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.baronedefensefirm.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.baronedefensefirm.com\/blog\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.baronedefensefirm.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.baronedefensefirm.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.baronedefensefirm.com\/blog\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}