{"id":88,"count":1,"description":"","link":"https:\/\/www.baronedefensefirm.com\/blog\/tag\/lara\/","name":"LARA","slug":"lara","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LARA Tag Archives &#8212; Michigan Criminal Defense Lawyer Blog<\/title>\n<meta name=\"description\" content=\"Michigan Criminal Defense Lawyer Blog &#8212; LARA Tag &#8212; Michigan Criminal Defense Lawyer Blog\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"LARA Tag Archives &#8212; Michigan Criminal Defense Lawyer Blog\" \/>\n<meta name=\"twitter:description\" content=\"Michigan Criminal Defense Lawyer Blog &#8212; LARA Tag &#8212; Michigan Criminal Defense Lawyer Blog\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LARA Tag Archives &#8212; Michigan Criminal Defense Lawyer Blog","description":"Michigan Criminal Defense Lawyer Blog &#8212; LARA Tag &#8212; Michigan Criminal Defense Lawyer Blog","robots":{"index":"noindex","follow":"follow"},"twitter_card":"summary_large_image","twitter_title":"LARA Tag Archives &#8212; Michigan Criminal Defense Lawyer Blog","twitter_description":"Michigan Criminal Defense Lawyer Blog &#8212; LARA Tag &#8212; Michigan Criminal Defense Lawyer Blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.baronedefensefirm.com\/blog\/tag\/lara\/","url":"https:\/\/www.baronedefensefirm.com\/blog\/tag\/lara\/","name":"LARA Tag Archives &#8212; Michigan Criminal Defense Lawyer Blog","isPartOf":{"@id":"https:\/\/www.baronedefensefirm.com\/blog\/#website"},"description":"Michigan Criminal Defense Lawyer Blog &#8212; LARA Tag &#8212; Michigan Criminal Defense Lawyer Blog","breadcrumb":{"@id":"https:\/\/www.baronedefensefirm.com\/blog\/tag\/lara\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.baronedefensefirm.com\/blog\/tag\/lara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.baronedefensefirm.com\/blog\/"},{"@type":"ListItem","position":2,"name":"LARA"}]},{"@type":"WebSite","@id":"https:\/\/www.baronedefensefirm.com\/blog\/#website","url":"https:\/\/www.baronedefensefirm.com\/blog\/","name":"Michigan Criminal Defense Lawyer Blog","description":"Published by Michigan Criminal Defense Attorney \u2014 Barone Defense Firm","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.baronedefensefirm.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.baronedefensefirm.com\/blog\/wp-json\/wp\/v2\/tags\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.baronedefensefirm.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.baronedefensefirm.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.baronedefensefirm.com\/blog\/wp-json\/wp\/v2\/posts?tags=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}